{"id":9104,"date":"2022-04-09T05:00:00","date_gmt":"2022-04-09T04:00:00","guid":{"rendered":"https:\/\/www.24-7prayer.com\/?p=9104"},"modified":"2022-04-08T18:21:40","modified_gmt":"2022-04-08T17:21:40","slug":"dietrich-bonhoeffer-heroe-de-la-justicia","status":"publish","type":"post","link":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/","title":{"rendered":"Dietrich Bonhoeffer: H\u00e9roe de la justicia"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<iframe loading=\"lazy\" style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/show\/6stSy5pU6jhldWvyb20Tew?utm_source=generator\" width=\"100%\" height=\"232\" frameborder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\"><\/iframe>\n\n\n\n<p>Hoy es s\u00e1bado, 9 de abril, d\u00eda de celebraci\u00f3n del te\u00f3logo Dietrich Bonhoeffer, que falleci\u00f3 tal d\u00eda como hoy en 1945. En los d\u00edas de celebraci\u00f3n nos detenemos para celebrar las historias y aprender de las vidas de los h\u00e9roes de la fe, cuyo testimonio colectivo encarna nuestras seis pr\u00e1cticas en el coraz\u00f3n de Lectio 365. \u00c9stas son: Oraci\u00f3n y creatividad, justicia y hospitalidad, aprendizaje y misi\u00f3n. Por ello, hoy damos gracias a Dios por el ejemplo extraordinario de Bonhoeffer, un h\u00e9roe dedicado a la justicia.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"haz-una-pausa\">Haz una pausa<\/h3>\n\n\n\n<p><strong><em><strong><em><strong><em><strong><em><strong><em>Ahora, al iniciar mi tiempo de oraci\u00f3n, hago una pausa para estar quieto; para respirar lentamente, para re-centrar mis sentidos, que se encuentran dispersos, delante de la presencia de Dios.<\/em><\/strong><\/em><\/strong><\/em><\/strong><\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"haz-una-pausa\">Oraci\u00f3n de Enfoque<\/h3>\n\n\n\n<p><em>Padre Dios: abre mis ojos, agita mi coraz\u00f3n y ens\u00e9\u00f1ame c\u00f3mo: \u2018Practicar la justicia, amar la misericordia, y humillarme ante\u2026\u2019 ti hoy. (Miqueas 6:8)<\/em><\/p>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"regocijarse-y-reflexionar\">Regocijarse y Reflexionar<\/h3>\n\n\n\n<p>Hoy escojo regocijarme en la justicia de Dios, uni\u00e9ndome a la alabanza ancestral de todo el pueblo de Dios en las palabras del Salmo 9&#8230;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Pero el&nbsp;Se\u00f1or&nbsp;reina para siempre;<br> &nbsp;&nbsp;&nbsp;&nbsp;desde su trono lleva a cabo el juicio. <br>Juzgar\u00e1 al mundo con justicia<br> &nbsp;&nbsp;&nbsp;&nbsp;y gobernar\u00e1 a las naciones con imparcialidad.<\/p><cite><strong>Salmo 9:7-8 (NTV)<\/strong><\/cite><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p>Dietrich Bonhoeffer era un pastor, te\u00f3logo y disidente antinazi que viv\u00eda en Alemania en la \u00e9poca de la Segunda Guerra Mundial.&nbsp;Cuando Hitler ascendi\u00f3 al poder en Europa, Bonhoeffer se pronunci\u00f3 en voz alta y de forma desafiante contra \u00e9l.&nbsp;Como resultado, a Bonhoeffer se le prohibi\u00f3 ense\u00f1ar p\u00fablicamente y se le oblig\u00f3 a pasar a la clandestinidad. Ense\u00f1\u00f3 a los estudiantes del seminario durante varios a\u00f1os hasta su detenci\u00f3n y encarcelamiento en 1943. De forma incre\u00edble, Bonhoeffer sigui\u00f3 ense\u00f1ando desde la c\u00e1rcel hasta que fue trasladado al campo de concentraci\u00f3n de Flossenb\u00fcrg.<br><br>Mientras estaba en Flossenb\u00fcrg, Bonhoeffer fue condenado a muerte, sin testigos, actas del proceso ni defensa. Fue ejecutado a los 39 a\u00f1os, justo un mes antes de que terminara la guerra. Algunas de sus palabras de despedida fueron: \u201c<em>Este es el final, para m\u00ed el principio de la vida<\/em>\u00ab.*<br><br>El legado de Bonhoeffer sigue vivo a trav\u00e9s de sus escritos y del poderoso testimonio de su postura desafiante contra la injusticia de su \u00e9poca.<br><br>Dietrich Bonhoeffer escribi\u00f3 una vez:&nbsp;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>\u2018Cuando un loco atraviesa las calles en un coche, puedo, como pastor que se encuentra en el lugar, hacer algo m\u00e1s que consolar o enterrar a los atropellados. Debo saltar delante del coche y detenerlo\u2019.**<\/p><cite><strong>Dietrich Bonhoeffer<\/strong><\/cite><\/blockquote>\n\n\n\n<p>El reto que Bonhoeffer lanza aqu\u00ed es profundo: no s\u00f3lo para todo pastor, sino para todo disc\u00edpulo cristiano.<\/p>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"apelar-pedir\"><strong>Apelar \/ Pedir<\/strong><\/h3>\n\n\n\n<p>Pienso en las cadenas de injusticia que existen en mi mundo actual. \u00bfAnte qu\u00e9 cuestiones de explotaci\u00f3n u opresi\u00f3n guardo silencio?&nbsp;<br><br><em>Dios: me desaf\u00edas no s\u00f3lo a preocuparme sino a actuar. Mu\u00e9strame ahora c\u00f3mo puedo unirme a ti para establecer la justicia y la libertad hoy.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p><em>Esp\u00edritu Santo: tr\u00e1eme a la mente un grupo de personas atrapadas en un ciclo de injusticia. Gu\u00edame en la oraci\u00f3n por la intervenci\u00f3n de Dios. Establece tu justicia y tu libertad.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"rendirse\"><strong>Rendirs<\/strong>e<\/h2>\n\n\n\n<p>Adem\u00e1s de su testimonio y sus ense\u00f1anzas sobre la justicia, Bonhoeffer tambi\u00e9n ense\u00f1\u00f3 poderosamente sobre el coste del discipulado. Instando a los cristianos a no conformarse con la \u00abgracia barata\u00bb, escribi\u00f3 que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La gracia costosa es el tesoro escondido en el campo; por ella un hombre ir\u00e1 con gusto a vender todo lo que tiene. Es costosa porque le cuesta al hombre su vida, y es gracia porque le da al hombre la \u00fanica vida verdadera.***<\/p><cite><strong>Dietrich Bonhoeffer<\/strong><\/cite><\/blockquote>\n\n\n\n<p>Me pregunto cu\u00e1nto me puede costar hoy mi fe en Jes\u00fas.&nbsp;<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong>Oraci\u00f3n de Rendici\u00f3n<\/strong><\/h3>\n\n\n\n<p><em>Dios de la justicia y de la gracia: me someto una vez m\u00e1s a la llamada omnipresente de tu evangelio: dar todo lo que tengo para ganar el verdadero tesoro que se encuentra en ti, y s\u00f3lo en ti.&nbsp;<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong><strong>Promesa de Rendici\u00f3n<\/strong><\/strong><\/h3>\n\n\n\n<p>Y ahora, mientras me preparo para llevar este tiempo de oraci\u00f3n al d\u00eda que tengo por delante, el Se\u00f1or, que me ama, dice en Isa\u00edas 30\u2026<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Por eso el&nbsp;Se\u00f1or&nbsp;os espera, para tener piedad de vosotros;<br> &nbsp;&nbsp;&nbsp;&nbsp;por eso se levanta para mostraros compasi\u00f3n. <br>Porque el&nbsp;Se\u00f1or&nbsp;es un Dios de justicia.<br> &nbsp;&nbsp;&nbsp;&nbsp;\u00a1Dichosos todos los que en \u00e9l esperan!<\/p><cite><strong><strong>Isa\u00edas 30:18 (NVI CST)<\/strong><\/strong><\/cite><\/blockquote>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong>Oraci\u00f3n para concluir<\/strong><\/h3>\n\n\n\n<p><strong>Padre, ay\u00fadame a vivir este d\u00eda al m\u00e1ximo, siendo aut\u00e9ntico contigo en todo. <\/strong><br><strong>Jes\u00fas, ay\u00fadame a darme a los dem\u00e1s, siendo amable con toda la gente con la que me encuentre. <\/strong><br><strong>Esp\u00edritu, ay\u00fadame a amar a la gente que se encuentra perdida, proclamando a Cristo en todo lo que digo y hago.&nbsp;<br>Am\u00e9n.<\/strong><br><br><\/p>\n\n\n\n<p>* Eberhard Bethge, <em>Dietrich Bonhoeffer: A Biography<\/em>, p.927.<\/p>\n\n\n\n<p>** Dietrich Bonhoeffer, citado por Hannah Ward, Hannah y Jennifer Wild, <em>The Lion Christian Quotation Collection<\/em> (BCA: London, 1997) p.204.<\/p>\n\n\n\n<p>*** Ibid p.204.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy es s\u00e1bado, 9 de abril, d\u00eda de celebraci\u00f3n del te\u00f3logo Dietrich Bonhoeffer, que falleci\u00f3 tal d\u00eda como hoy en 1945. En los d\u00edas de celebraci\u00f3n nos detenemos para celebrar las historias y aprender de las vidas de los h\u00e9roes de la fe, cuyo testimonio colectivo encarna nuestras seis pr\u00e1cticas en el coraz\u00f3n de Lectio [&hellip;]<\/p>\n","protected":false},"author":216,"featured_media":8621,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[206],"tags":[],"author_slug":[370],"blog_series":[383],"topic":[353],"class_list":["post-9104","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","author_slug-oracion-24-7","blog_series-la-pasion","topic-orar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Dietrich Bonhoeffer: H\u00e9roe de la justicia<\/title>\n<meta name=\"description\" content=\"Dietrich Bonhoeffer, escribi\u00f3 antes de morir: Este es el final, para m\u00ed el principio de la vida.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Dietrich Bonhoeffer: H\u00e9roe de la justicia\" \/>\n<meta property=\"og:description\" content=\"Dietrich Bonhoeffer, escribi\u00f3 antes de morir: Este es el final, para m\u00ed el principio de la vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/\" \/>\n<meta property=\"og:site_name\" content=\"24-7 Prayer International\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-09T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aitor@oracion24-7.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/\"},\"author\":{\"name\":\"aitor@oracion24-7.com\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/person\\\/cea924691d05af4dfa35da709e7ede7d\"},\"headline\":\"Dietrich Bonhoeffer: H\u00e9roe de la justicia\",\"datePublished\":\"2022-04-09T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/\"},\"wordCount\":920,\"publisher\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"articleSection\":[\"Blogs\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/\",\"name\":\"Dietrich Bonhoeffer: H\u00e9roe de la justicia\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"datePublished\":\"2022-04-09T04:00:00+00:00\",\"description\":\"Dietrich Bonhoeffer, escribi\u00f3 antes de morir: Este es el final, para m\u00ed el principio de la vida.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/dietrich-bonhoeffer-heroe-de-la-justicia\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Dietrich Bonhoeffer: H\u00e9roe de la justicia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\",\"name\":\"24-7 Prayer International\",\"description\":\"Prayer Mission Justice\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\",\"name\":\"24-7 Prayer\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo.png\",\"width\":302,\"height\":49,\"caption\":\"24-7 Prayer\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/person\\\/cea924691d05af4dfa35da709e7ede7d\",\"name\":\"aitor@oracion24-7.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"caption\":\"aitor@oracion24-7.com\"},\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/author\\\/aitororacion24-7-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Dietrich Bonhoeffer: H\u00e9roe de la justicia","description":"Dietrich Bonhoeffer, escribi\u00f3 antes de morir: Este es el final, para m\u00ed el principio de la vida.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/","og_locale":"es_ES","og_type":"article","og_title":"Dietrich Bonhoeffer: H\u00e9roe de la justicia","og_description":"Dietrich Bonhoeffer, escribi\u00f3 antes de morir: Este es el final, para m\u00ed el principio de la vida.","og_url":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/","og_site_name":"24-7 Prayer International","article_published_time":"2022-04-09T04:00:00+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","type":"image\/jpeg"}],"author":"aitor@oracion24-7.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/#article","isPartOf":{"@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/"},"author":{"name":"aitor@oracion24-7.com","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/person\/cea924691d05af4dfa35da709e7ede7d"},"headline":"Dietrich Bonhoeffer: H\u00e9roe de la justicia","datePublished":"2022-04-09T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/"},"wordCount":920,"publisher":{"@id":"https:\/\/www.24-7prayer.com\/es\/#organization"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","articleSection":["Blogs"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/","url":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/","name":"Dietrich Bonhoeffer: H\u00e9roe de la justicia","isPartOf":{"@id":"https:\/\/www.24-7prayer.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/#primaryimage"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","datePublished":"2022-04-09T04:00:00+00:00","description":"Dietrich Bonhoeffer, escribi\u00f3 antes de morir: Este es el final, para m\u00ed el principio de la vida.","breadcrumb":{"@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/#primaryimage","url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","contentUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.24-7prayer.com\/es\/dietrich-bonhoeffer-heroe-de-la-justicia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.24-7prayer.com\/es\/"},{"@type":"ListItem","position":2,"name":"Dietrich Bonhoeffer: H\u00e9roe de la justicia"}]},{"@type":"WebSite","@id":"https:\/\/www.24-7prayer.com\/es\/#website","url":"https:\/\/www.24-7prayer.com\/es\/","name":"24-7 Prayer International","description":"Prayer Mission Justice","publisher":{"@id":"https:\/\/www.24-7prayer.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.24-7prayer.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.24-7prayer.com\/es\/#organization","name":"24-7 Prayer","url":"https:\/\/www.24-7prayer.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/06\/logo.png","contentUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/06\/logo.png","width":302,"height":49,"caption":"24-7 Prayer"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/person\/cea924691d05af4dfa35da709e7ede7d","name":"aitor@oracion24-7.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","caption":"aitor@oracion24-7.com"},"url":"https:\/\/www.24-7prayer.com\/es\/author\/aitororacion24-7-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/9104","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/comments?post=9104"}],"version-history":[{"count":6,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/9104\/revisions"}],"predecessor-version":[{"id":9131,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/9104\/revisions\/9131"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/media\/8621"}],"wp:attachment":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/media?parent=9104"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/categories?post=9104"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/tags?post=9104"},{"taxonomy":"author_slug","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/author_slug?post=9104"},{"taxonomy":"blog_series","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/blog_series?post=9104"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/topic?post=9104"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}