{"id":9096,"date":"2022-04-07T05:00:00","date_gmt":"2022-04-07T04:00:00","guid":{"rendered":"https:\/\/www.24-7prayer.com\/?p=9096"},"modified":"2022-04-06T23:13:17","modified_gmt":"2022-04-06T22:13:17","slug":"el-poder-del-pueblo","status":"publish","type":"post","link":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/","title":{"rendered":"El poder del pueblo"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<iframe loading=\"lazy\" style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/show\/6stSy5pU6jhldWvyb20Tew?utm_source=generator\" width=\"100%\" height=\"232\" frameborder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\"><\/iframe>\n\n\n\n<p>Hoy es jueves, 7 de abril y esta semana continuamos con nuestra serie sobre La Pasi\u00f3n, orando a trav\u00e9s del relato de Mateo sobre el viaje de Jes\u00fas a la cruz.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"haz-una-pausa\">Haz una pausa<\/h3>\n\n\n\n<p><strong><em><strong><em><strong><em><strong><em><strong><em>Ahora, al iniciar mi tiempo de oraci\u00f3n, hago una pausa para estar quieta; para respirar lentamente, para re-centrar mis sentidos, que se encuentran dispersos, delante de la presencia de Dios.<\/em><\/strong><\/em><\/strong><\/em><\/strong><\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"haz-una-pausa\">Oraci\u00f3n de Enfoque<\/h3>\n\n\n\n<p><em><em><em><em>Jes\u00fas, T\u00fa eres el camino, la verdad y la vida. A trav\u00e9s de esta \u00e9poca de Cuaresma, mientras medito en tu Santa Pasi\u00f3n, que mi amor sea reavivado, para que pueda vivir sacrificada y enteramente para Ti.<\/em><\/em><\/em><\/em><\/p>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"regocijarse-y-reflexionar\">Regocijarse y Reflexionar<\/h3>\n\n\n\n<p>Hoy escojo regocijarme en los planes pacientes de Dios, uni\u00e9ndome a la alabanza ancestral de todo el pueblo de Dios en las palabras del Salmo 118&#8230;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>La piedra que los constructores rechazaron<br> &nbsp;&nbsp;&nbsp;&nbsp;ahora se ha convertido en la piedra principal. <br>Esto es obra del&nbsp;Se\u00f1or<br> &nbsp;&nbsp;&nbsp;&nbsp;y es maravilloso verlo. <br>Este es el d\u00eda que hizo el&nbsp;Se\u00f1or;<br> &nbsp;&nbsp;&nbsp;&nbsp;nos gozaremos y alegraremos en \u00e9l.<\/p><cite><strong>Salmo 118:22-24 (NTV)<\/strong><\/cite><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p>Hoy sigo reflexionando sobre el juicio de Jes\u00fas ante el gobernador romano, Pilato&#8230;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Mientras Pilato estaba sentado en el tribunal, su esposa le envi\u00f3 el siguiente recado: \u00abNo te metas con ese justo, pues, por causa de \u00e9l, hoy he sufrido mucho en un sue\u00f1o\u00bb. <br>Pero los jefes de los sacerdotes y los ancianos persuadieron a la multitud a que le pidiera a Pilato soltar a Barrab\u00e1s y ejecutar a Jes\u00fas. <br>\u2015\u00bfA cu\u00e1l de los dos quer\u00e9is que os suelte? \u2014pregunt\u00f3 el gobernador. <br>\u2015A Barrab\u00e1s.<\/p><cite><strong>Mateo 27:19-21 (NVI CST)<\/strong><\/cite><\/blockquote>\n\n\n\n<p>\u00bfEn qu\u00e9 habr\u00eda sido diferente el papel de Pilato en esta historia si hubiera escuchado a su esposa? Si Pilato hubiera hecho caso a su sue\u00f1o, podr\u00eda haber utilizado su poder para evitar una injusticia. Pero, en cambio, ignor\u00f3 su advertencia y deleg\u00f3 la responsabilidad, permitiendo que una multitud f\u00e1cilmente manipulada decidiera el destino de un hombre.&nbsp;<\/p>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"apelar-pedir\"><strong>Apelar \/ Pedir<\/strong><\/h3>\n\n\n\n<p>Me pregunto si el sue\u00f1o de la mujer de Pilato proven\u00eda de Dios.<br><br><em>Dios: s\u00e9 que puedes hablar a trav\u00e9s de los sue\u00f1os. Recu\u00e9rdame los sue\u00f1os que me has dado en el pasado. Te invito a hablar a trav\u00e9s de mi subconsciente esta noche.&nbsp;<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p><em>Te pido por los que trabajan en el sistema judicial que, como Pilato, tienen el poder de decidir el destino de una persona. Dios: pienso en el tribunal m\u00e1s cercano a m\u00ed y te pido que aumentes la sabidur\u00eda, la compasi\u00f3n y el valor de los jueces que lo presiden.\u00a0<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"rendirse\"><strong>Rendirs<\/strong>e<\/h2>\n\n\n\n<p><strong><em>Al volver al pasaje, abro mis o\u00eddos para escuchar tu Palabra, y mi coraz\u00f3n para rendirme a tu voluntad una vez m\u00e1s\u2026<\/em><\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Mientras Pilato estaba sentado en el tribunal, su esposa le envi\u00f3 el siguiente recado: \u00abNo te metas con ese justo, pues, por causa de \u00e9l, hoy he sufrido mucho en un sue\u00f1o\u00bb. <br>Pero los jefes de los sacerdotes y los ancianos persuadieron a la multitud a que le pidiera a Pilato soltar a Barrab\u00e1s y ejecutar a Jes\u00fas. <br>\u2015\u00bfA cu\u00e1l de los dos quer\u00e9is que os suelte? \u2014pregunt\u00f3 el gobernador. <br>\u2015A Barrab\u00e1s.<\/p><cite><strong>Mateo 27:19-21 (NVI CST)<\/strong><\/cite><\/blockquote>\n\n\n\n<p>Es f\u00e1cil juzgar a Pilato por su inacci\u00f3n, pero a veces puedo permanecer pasiva cuando tengo el poder de evitar la injusticia. \u00bfC\u00f3mo puedo utilizar mi poder para actuar en favor de la justicia, ya sea en la cultura de mi lugar de trabajo, en la vida de las personas m\u00e1s desfavorecidas de mi comunidad o en otro \u00e1mbito de mi vida?<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong>Oraci\u00f3n de Rendici\u00f3n<\/strong><\/h3>\n\n\n\n<p><em>Jes\u00fas: mi juicio es err\u00f3neo. Yo, como Pilato, puedo dejarme llevar por las opiniones de la multitud. Dame valor para tomar decisiones impopulares cuando sea lo correcto.<\/em><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong><strong>Promesa de Rendici\u00f3n<\/strong><\/strong><\/h3>\n\n\n\n<p>Y ahora, mientras me preparo para llevar este tiempo de oraci\u00f3n al d\u00eda que tengo por delante, el Se\u00f1or, que me ama, dice en el evangelio de Juan:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>En verdad os digo que el que oye mi palabra y cree al que me ha enviado tiene vida eterna y no ser\u00e1 juzgado, sino que ha pasado de la muerte a la vida.<\/p><cite><strong>Juan 5:24<\/strong><\/cite><\/blockquote>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong>Oraci\u00f3n para concluir<\/strong><\/h3>\n\n\n\n<p><strong>Padre, ay\u00fadame a vivir este d\u00eda al m\u00e1ximo, siendo aut\u00e9ntico contigo en todo. <\/strong><br><strong>Jes\u00fas, ay\u00fadame a darme a los dem\u00e1s, siendo amable con toda la gente con la que me encuentre. <\/strong><br><strong>Esp\u00edritu, ay\u00fadame a amar a la gente que se encuentra perdida, proclamando a Cristo en todo lo que digo y hago.&nbsp;<br>Am\u00e9n.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy es jueves, 7 de abril y esta semana continuamos con nuestra serie sobre La Pasi\u00f3n, orando a trav\u00e9s del relato de Mateo sobre el viaje de Jes\u00fas a la cruz. Haz una pausa Ahora, al iniciar mi tiempo de oraci\u00f3n, hago una pausa para estar quieta; para respirar lentamente, para re-centrar mis sentidos, que [&hellip;]<\/p>\n","protected":false},"author":216,"featured_media":8621,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[206],"tags":[],"author_slug":[370],"blog_series":[383],"topic":[353],"class_list":["post-9096","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","author_slug-oracion-24-7","blog_series-la-pasion","topic-orar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El poder del pueblo<\/title>\n<meta name=\"description\" content=\"\u00bfPermanezco pasivo cuando tengo el poder de evitar la injusticia?\u00a0\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El poder del pueblo\" \/>\n<meta property=\"og:description\" content=\"\u00bfPermanezco pasivo cuando tengo el poder de evitar la injusticia?\u00a0\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/\" \/>\n<meta property=\"og:site_name\" content=\"24-7 Prayer International\" \/>\n<meta property=\"article:published_time\" content=\"2022-04-07T04:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aitor@oracion24-7.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/\"},\"author\":{\"name\":\"aitor@oracion24-7.com\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/person\\\/cea924691d05af4dfa35da709e7ede7d\"},\"headline\":\"El poder del pueblo\",\"datePublished\":\"2022-04-07T04:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/\"},\"wordCount\":837,\"publisher\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"articleSection\":[\"Blogs\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/\",\"name\":\"El poder del pueblo\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"datePublished\":\"2022-04-07T04:00:00+00:00\",\"description\":\"\u00bfPermanezco pasivo cuando tengo el poder de evitar la injusticia?\u00a0\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/el-poder-del-pueblo\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El poder del pueblo\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\",\"name\":\"24-7 Prayer International\",\"description\":\"Prayer Mission Justice\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\",\"name\":\"24-7 Prayer\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo.png\",\"width\":302,\"height\":49,\"caption\":\"24-7 Prayer\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/person\\\/cea924691d05af4dfa35da709e7ede7d\",\"name\":\"aitor@oracion24-7.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"caption\":\"aitor@oracion24-7.com\"},\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/author\\\/aitororacion24-7-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El poder del pueblo","description":"\u00bfPermanezco pasivo cuando tengo el poder de evitar la injusticia?\u00a0","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/","og_locale":"es_ES","og_type":"article","og_title":"El poder del pueblo","og_description":"\u00bfPermanezco pasivo cuando tengo el poder de evitar la injusticia?\u00a0","og_url":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/","og_site_name":"24-7 Prayer International","article_published_time":"2022-04-07T04:00:00+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","type":"image\/jpeg"}],"author":"aitor@oracion24-7.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/#article","isPartOf":{"@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/"},"author":{"name":"aitor@oracion24-7.com","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/person\/cea924691d05af4dfa35da709e7ede7d"},"headline":"El poder del pueblo","datePublished":"2022-04-07T04:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/"},"wordCount":837,"publisher":{"@id":"https:\/\/www.24-7prayer.com\/es\/#organization"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","articleSection":["Blogs"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/","url":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/","name":"El poder del pueblo","isPartOf":{"@id":"https:\/\/www.24-7prayer.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/#primaryimage"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/#primaryimage"},"thumbnailUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","datePublished":"2022-04-07T04:00:00+00:00","description":"\u00bfPermanezco pasivo cuando tengo el poder de evitar la injusticia?\u00a0","breadcrumb":{"@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/#primaryimage","url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","contentUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.24-7prayer.com\/es\/el-poder-del-pueblo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.24-7prayer.com\/es\/"},{"@type":"ListItem","position":2,"name":"El poder del pueblo"}]},{"@type":"WebSite","@id":"https:\/\/www.24-7prayer.com\/es\/#website","url":"https:\/\/www.24-7prayer.com\/es\/","name":"24-7 Prayer International","description":"Prayer Mission Justice","publisher":{"@id":"https:\/\/www.24-7prayer.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.24-7prayer.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.24-7prayer.com\/es\/#organization","name":"24-7 Prayer","url":"https:\/\/www.24-7prayer.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/06\/logo.png","contentUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/06\/logo.png","width":302,"height":49,"caption":"24-7 Prayer"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/person\/cea924691d05af4dfa35da709e7ede7d","name":"aitor@oracion24-7.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","caption":"aitor@oracion24-7.com"},"url":"https:\/\/www.24-7prayer.com\/es\/author\/aitororacion24-7-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/9096","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/comments?post=9096"}],"version-history":[{"count":5,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/9096\/revisions"}],"predecessor-version":[{"id":9109,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/9096\/revisions\/9109"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/media\/8621"}],"wp:attachment":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/media?parent=9096"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/categories?post=9096"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/tags?post=9096"},{"taxonomy":"author_slug","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/author_slug?post=9096"},{"taxonomy":"blog_series","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/blog_series?post=9096"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/topic?post=9096"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}