{"id":8867,"date":"2022-03-16T05:00:00","date_gmt":"2022-03-16T05:00:00","guid":{"rendered":"https:\/\/www.24-7prayer.com\/?p=8867"},"modified":"2022-03-15T21:06:34","modified_gmt":"2022-03-15T21:06:34","slug":"fe-enfriada","status":"publish","type":"post","link":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/","title":{"rendered":"La fe se ha enfriado"},"content":{"rendered":"\n<div class=\"wp-block-buttons is-content-justification-center is-layout-flex wp-container-core-buttons-is-layout-a89b3969 wp-block-buttons-is-layout-flex\"><\/div>\n\n\n\n<iframe loading=\"lazy\" style=\"border-radius:12px\" src=\"https:\/\/open.spotify.com\/embed\/show\/6stSy5pU6jhldWvyb20Tew?utm_source=generator\" width=\"100%\" height=\"232\" frameborder=\"0\" allowfullscreen=\"\" allow=\"autoplay; clipboard-write; encrypted-media; fullscreen; picture-in-picture\"><\/iframe>\n\n\n\n<p>Hoy es mi\u00e9rcoles, 16 de marzo, y esta semana estamos meditando en los acontecimientos que tuvieron lugar el d\u00eda antes a la crucifixi\u00f3n de Jes\u00fas, seg\u00fan los narra  el libro de Mateo.<\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"haz-una-pausa\">Haz una pausa<\/h3>\n\n\n\n<p><strong><em><strong><em><strong><em><strong><em><strong><em>Ahora, al iniciar mi tiempo de oraci\u00f3n, hago una pausa para estar quieto; para respirar lentamente, para re-centrar mis sentidos, que se encuentran dispersos, delante de la presencia de Dios.<\/em><\/strong><\/em><\/strong><\/em><\/strong><\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"haz-una-pausa\">Oraci\u00f3n de Enfoque<\/h3>\n\n\n\n<p><em><em><em><em>Jes\u00fas, T\u00fa eres el camino, la verdad y la vida. A trav\u00e9s de esta \u00e9poca de Cuaresma, mientras medito en tu Santa Pasi\u00f3n, que mi amor sea reavivado, para que pueda vivir sacrificada y enteramente para Ti.<\/em><\/em><\/em><\/em><\/p>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"regocijarse-y-reflexionar\">Regocijarse y Reflexionar<\/h3>\n\n\n\n<p>Hoy escojo regocijarme en la gracia de Dios, uni\u00e9ndome a la alabanza ancestral de todo el pueblo de Dios en las palabras del Salmo 103&#8230;<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El&nbsp;Se\u00f1or&nbsp;es compasivo y misericordioso,<br> &nbsp;&nbsp;&nbsp;&nbsp;lento para enojarse y est\u00e1 lleno de amor inagotable. <br>No nos reprender\u00e1 todo el tiempo<br> &nbsp;&nbsp;&nbsp;&nbsp;ni seguir\u00e1 enojado para siempre. <br>No nos castiga por todos nuestros pecados;<br> &nbsp;&nbsp;&nbsp;&nbsp;no nos trata con la severidad que merecemos. <br>Pues su amor inagotable hacia los que le temen<br> &nbsp;&nbsp;&nbsp;&nbsp;es tan inmenso como la altura de los cielos sobre la tierra.<\/p><cite><strong><strong><strong><strong><strong><strong><strong><strong>Salmo 103:8-11 (NTV)<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/cite><\/blockquote>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p>Hoy medito en las consecuencias de la \u00daltima Cena, cuando Jes\u00fas y sus disc\u00edpulos abandonaron el lugar donde hab\u00edan estado cenando juntos\u2026<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Despu\u00e9s de cantar los salmos, salieron al monte de los Olivos. <br>\u2015Esta misma noche \u2014les dijo Jes\u00fas\u2014 todos vosotros me abandonar\u00e9is, porque est\u00e1 escrito: \u00bb\u201cHerir\u00e9 al pastor,<br> &nbsp;&nbsp;&nbsp;&nbsp;y se dispersar\u00e1n las ovejas del reba\u00f1o\u201d. <br>Pero, despu\u00e9s de que yo haya resucitado, ir\u00e9 delante de vosotros a Galilea\u00bb. <br>\u2015Aunque todos te abandonen \u2014declar\u00f3 Pedro\u2014, yo jam\u00e1s lo har\u00e9. \u2015Te aseguro \u2014le contest\u00f3 Jes\u00fas\u2014 que esta misma noche, antes de que cante el gallo, me negar\u00e1s tres veces. <br>\u2015Aunque tenga que morir contigo \u2014insisti\u00f3 Pedro\u2014, jam\u00e1s te negar\u00e9. <br>Y los dem\u00e1s disc\u00edpulos dijeron lo mismo.<\/p><cite><strong><strong><strong><strong><strong><strong><strong><strong>Mateo 26:30-35 (NVI CST)<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/cite><\/blockquote>\n\n\n\n<p>Los disc\u00edpulos estaban perturbados y confundidos. Su comida juntos no hab\u00eda sido la celebraci\u00f3n de la Pascua que esperaban, y Jes\u00fas hab\u00eda dicho y hecho algunas cosas extra\u00f1as. Y luego, para colmo, les dijo: &#8216;esta misma noche, todos vosotros me abandonar\u00e9is\u2019.<br><br>La verdad es que me he \u00abalejado\u00bb muchas veces. Tal vez no he negado rotundamente que soy un seguidor de Jes\u00fas, como Pedro estaba a punto de hacer. Y a lo mejor no he huido con miedo, como lo har\u00e1n pronto los otros disc\u00edpulos. Pero a veces he dejado que mi fe se enfr\u00ede.&nbsp;<\/p>\n\n\n\n<div style=\"height:59px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"apelar-pedir\"><strong>Apelar \/ Pedir<\/strong><\/h3>\n\n\n\n<p>\u00bfC\u00f3mo me siento ahora? \u00bfEstoy lleno de fe, \u00abardiendo\u00bb por Jes\u00fas, o el fuego ha menguado? \u00bfMe he \u00abalejado\u00bb de seguir a Jes\u00fas de alguna manera?<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<p>\u00bfA qui\u00e9n conozco que parece haberse \u00abalejado\u00bb en cuanto a seguir a Jes\u00fas se refiere? \u00bfQuiz\u00e1s un amigo o un familiar? \u00bfIgual un hijo que parece menos interesado ahora que ha llegado a la adolescencia?<br><br><em>Se\u00f1or Jes\u00fas: nombro a estos seres queridos en silencio ante Ti ahora e intercedo por ellos. Te pido que su amor por ti se reavive.<\/em><\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h2 class=\"wp-block-heading\" id=\"rendirse\"><strong>Rendirs<\/strong>e<\/h2>\n\n\n\n<p><strong><em><strong><em>Al volver al pasaje, abro mis o\u00eddos para escuchar tu Palabra, y mi coraz\u00f3n para rendirme a tu voluntad una vez m\u00e1s.<\/em><\/strong><\/em><\/strong><\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>Despu\u00e9s de cantar los salmos, salieron al monte de los Olivos. <br>\u2015Esta misma noche \u2014les dijo Jes\u00fas\u2014 todos vosotros me abandonar\u00e9is, porque est\u00e1 escrito: \u00bb\u201cHerir\u00e9 al pastor,<br> &nbsp;&nbsp;&nbsp;&nbsp;y se dispersar\u00e1n las ovejas del reba\u00f1o\u201d. <br>Pero, despu\u00e9s de que yo haya resucitado, ir\u00e9 delante de vosotros a Galilea\u00bb. <br>\u2015Aunque todos te abandonen \u2014declar\u00f3 Pedro\u2014, yo jam\u00e1s lo har\u00e9. \u2015Te aseguro \u2014le contest\u00f3 Jes\u00fas\u2014 que esta misma noche, antes de que cante el gallo, me negar\u00e1s tres veces. <br>\u2015Aunque tenga que morir contigo \u2014insisti\u00f3 Pedro\u2014, jam\u00e1s te negar\u00e9. <br>Y los dem\u00e1s disc\u00edpulos dijeron lo mismo.<\/p><cite><strong><strong><strong><strong><strong><strong><strong><strong>Mateo 26:30-35 (NVI CST)<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/cite><\/blockquote>\n\n\n\n<p>Habiendo celebrado La Pascua juntos, es probable que el himno que cantaron Jes\u00fas y sus disc\u00edpulos fuera el Salmo 118. Dado que Jes\u00fas va a ser arrestado pronto, torturado y crucificado, las palabras del Salmo son a\u00fan m\u00e1s conmovedoras: \u2018Dad gracias al&nbsp;Se\u00f1or, porque \u00e9l es bueno; su gran amor perdura para siempre\u2019. (Salmo 118:1, NVI CST)<\/p>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h5 class=\"has-text-align-center wp-block-heading\" id=\"haz-una-pausa-y-ora\"><em>Haz una pausa y ora<\/em><\/h5>\n\n\n\n<hr class=\"wp-block-separator is-style-dots\"\/>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong>Oraci\u00f3n de Rendici\u00f3n<\/strong><\/h3>\n\n\n\n<p><em>Utilizando algunos vers\u00edculos m\u00e1s del Salmo 118 como mi oraci\u00f3n, me rindo a la bondad de Dios:<\/em><br><br><em>\u2018Cuando me siento presionado, clamo a ti, Se\u00f1or, y me llevas a un lugar espacioso. T\u00fa est\u00e1s conmigo; no tendr\u00e9 miedo. \u00bfQu\u00e9 pueden hacerme los simples mortales? T\u00fa est\u00e1s conmigo&#8230; Te doy gracias, porque eres bueno, tu amor es eterno.\u2019<\/em>\u00a0<br>(Adaptado del Salmo 118: 5-7a,1, NVI CST)<br><\/p>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong><strong>Promesa de Rendici\u00f3n<\/strong><\/strong><\/h3>\n\n\n\n<p>Y ahora, mientras me preparo para llevar este tiempo de oraci\u00f3n al d\u00eda que tengo por delante, el Se\u00f1or, que me ama dice en 1 de Pedro que:<\/p>\n\n\n\n<blockquote class=\"wp-block-quote is-layout-flow wp-block-quote-is-layout-flow\"><p>El Dios de toda gracia, que [me] llam\u00f3 a su gloria eterna en Cristo, despu\u00e9s de que [yo] haya sufrido durante un tiempo, [me] restaurar\u00e1 y [me] har\u00e1 fuerte, firme y estable.<\/p><cite><strong><strong><strong><strong><strong><strong><strong><strong>1 Pedro 5:10 (NVI CST)<\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/strong><\/cite><\/blockquote>\n\n\n\n<div style=\"height:28px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h3 class=\"wp-block-heading\" id=\"oracion-de-rendicion\"><strong>Oraci\u00f3n para concluir<\/strong><\/h3>\n\n\n\n<p><strong>Padre, ay\u00fadame a vivir este d\u00eda al m\u00e1ximo, siendo aut\u00e9ntico contigo en todo. <\/strong><br><strong>Jes\u00fas, ay\u00fadame a darme a los dem\u00e1s, siendo amable con toda la gente con la que me encuentre. <\/strong><br><strong>Esp\u00edritu, ay\u00fadame a amar a la gente que se encuentra perdida, proclamando a Cristo en todo lo que digo y hago.&nbsp;<br>Am\u00e9n.<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy es mi\u00e9rcoles, 16 de marzo, y esta semana estamos meditando en los acontecimientos que tuvieron lugar el d\u00eda antes a la crucifixi\u00f3n de Jes\u00fas, seg\u00fan los narra el libro de Mateo. Haz una pausa Ahora, al iniciar mi tiempo de oraci\u00f3n, hago una pausa para estar quieto; para respirar lentamente, para re-centrar mis sentidos, [&hellip;]<\/p>\n","protected":false},"author":216,"featured_media":8621,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"categories":[206],"tags":[],"author_slug":[370],"blog_series":[383],"topic":[353],"class_list":["post-8867","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-blog-es","author_slug-oracion-24-7","blog_series-la-pasion","topic-orar"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La fe se ha enfriado - 24-7 Prayer International<\/title>\n<meta name=\"description\" content=\"\u00bfEstoy lleno de fe - \u2018encendido\u2019 para Jes\u00fas - o se ha apagado el fuego?\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La fe se ha enfriado - 24-7 Prayer International\" \/>\n<meta property=\"og:description\" content=\"\u00bfEstoy lleno de fe - \u2018encendido\u2019 para Jes\u00fas - o se ha apagado el fuego?\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/\" \/>\n<meta property=\"og:site_name\" content=\"24-7 Prayer International\" \/>\n<meta property=\"article:published_time\" content=\"2022-03-16T05:00:00+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"2560\" \/>\n\t<meta property=\"og:image:height\" content=\"1440\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"aitor@oracion24-7.com\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/\"},\"author\":{\"name\":\"aitor@oracion24-7.com\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/person\\\/cea924691d05af4dfa35da709e7ede7d\"},\"headline\":\"La fe se ha enfriado\",\"datePublished\":\"2022-03-16T05:00:00+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/\"},\"wordCount\":1010,\"publisher\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"articleSection\":[\"Blogs\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/\",\"name\":\"La fe se ha enfriado - 24-7 Prayer International\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"datePublished\":\"2022-03-16T05:00:00+00:00\",\"description\":\"\u00bfEstoy lleno de fe - \u2018encendido\u2019 para Jes\u00fas - o se ha apagado el fuego?\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"contentUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/03\\\/La-pasion-Lectio-2560x1280-1.jpg\",\"width\":2560,\"height\":1440},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/fe-enfriada\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La fe se ha enfriado\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\",\"name\":\"24-7 Prayer International\",\"description\":\"Prayer Mission Justice\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#organization\",\"name\":\"24-7 Prayer\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo.png\",\"contentUrl\":\"https:\\\/\\\/www.24-7prayer.com\\\/wp-content\\\/uploads\\\/2022\\\/06\\\/logo.png\",\"width\":302,\"height\":49,\"caption\":\"24-7 Prayer\"},\"image\":{\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/#\\\/schema\\\/person\\\/cea924691d05af4dfa35da709e7ede7d\",\"name\":\"aitor@oracion24-7.com\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g\",\"caption\":\"aitor@oracion24-7.com\"},\"url\":\"https:\\\/\\\/www.24-7prayer.com\\\/es\\\/author\\\/aitororacion24-7-com\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La fe se ha enfriado - 24-7 Prayer International","description":"\u00bfEstoy lleno de fe - \u2018encendido\u2019 para Jes\u00fas - o se ha apagado el fuego?","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/","og_locale":"es_ES","og_type":"article","og_title":"La fe se ha enfriado - 24-7 Prayer International","og_description":"\u00bfEstoy lleno de fe - \u2018encendido\u2019 para Jes\u00fas - o se ha apagado el fuego?","og_url":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/","og_site_name":"24-7 Prayer International","article_published_time":"2022-03-16T05:00:00+00:00","og_image":[{"width":2560,"height":1440,"url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","type":"image\/jpeg"}],"author":"aitor@oracion24-7.com","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/#article","isPartOf":{"@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/"},"author":{"name":"aitor@oracion24-7.com","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/person\/cea924691d05af4dfa35da709e7ede7d"},"headline":"La fe se ha enfriado","datePublished":"2022-03-16T05:00:00+00:00","mainEntityOfPage":{"@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/"},"wordCount":1010,"publisher":{"@id":"https:\/\/www.24-7prayer.com\/es\/#organization"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","articleSection":["Blogs"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/","url":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/","name":"La fe se ha enfriado - 24-7 Prayer International","isPartOf":{"@id":"https:\/\/www.24-7prayer.com\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/#primaryimage"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/#primaryimage"},"thumbnailUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","datePublished":"2022-03-16T05:00:00+00:00","description":"\u00bfEstoy lleno de fe - \u2018encendido\u2019 para Jes\u00fas - o se ha apagado el fuego?","breadcrumb":{"@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/#primaryimage","url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","contentUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/03\/La-pasion-Lectio-2560x1280-1.jpg","width":2560,"height":1440},{"@type":"BreadcrumbList","@id":"https:\/\/www.24-7prayer.com\/es\/fe-enfriada\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.24-7prayer.com\/es\/"},{"@type":"ListItem","position":2,"name":"La fe se ha enfriado"}]},{"@type":"WebSite","@id":"https:\/\/www.24-7prayer.com\/es\/#website","url":"https:\/\/www.24-7prayer.com\/es\/","name":"24-7 Prayer International","description":"Prayer Mission Justice","publisher":{"@id":"https:\/\/www.24-7prayer.com\/es\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.24-7prayer.com\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.24-7prayer.com\/es\/#organization","name":"24-7 Prayer","url":"https:\/\/www.24-7prayer.com\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/06\/logo.png","contentUrl":"https:\/\/www.24-7prayer.com\/wp-content\/uploads\/2022\/06\/logo.png","width":302,"height":49,"caption":"24-7 Prayer"},"image":{"@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/www.24-7prayer.com\/es\/#\/schema\/person\/cea924691d05af4dfa35da709e7ede7d","name":"aitor@oracion24-7.com","image":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/e67a3b0c8e0d52ee179e9f94d3d54543d229c4da1d7def06a61faccb28313f0a?s=96&d=mm&r=g","caption":"aitor@oracion24-7.com"},"url":"https:\/\/www.24-7prayer.com\/es\/author\/aitororacion24-7-com\/"}]}},"_links":{"self":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/8867","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/users\/216"}],"replies":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/comments?post=8867"}],"version-history":[{"count":4,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/8867\/revisions"}],"predecessor-version":[{"id":8872,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/posts\/8867\/revisions\/8872"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/media\/8621"}],"wp:attachment":[{"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/media?parent=8867"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/categories?post=8867"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/tags?post=8867"},{"taxonomy":"author_slug","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/author_slug?post=8867"},{"taxonomy":"blog_series","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/blog_series?post=8867"},{"taxonomy":"topic","embeddable":true,"href":"https:\/\/www.24-7prayer.com\/es\/wp-json\/wp\/v2\/topic?post=8867"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}